{"id":233,"count":1,"description":"","link":"https:\/\/laspezieriadellaseta.it\/en\/t\/profumo-fresco\/","name":"profumo fresco","slug":"profumo-fresco","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>profumo fresco Archivi - La Spezieria della Seta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laspezieriadellaseta.it\/en\/t\/profumo-fresco\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"profumo fresco Archivi - La Spezieria della Seta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laspezieriadellaseta.it\/en\/t\/profumo-fresco\/\" \/>\n<meta property=\"og:site_name\" content=\"La Spezieria della Seta\" \/>\n<meta property=\"og:image\" content=\"https:\/\/laspezieriadellaseta.it\/wp-content\/uploads\/2025\/01\/la-spezieria-della-seta-profumeria-artistica-soffio-duchaufour-G-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/t\\\/profumo-fresco\\\/\",\"url\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/t\\\/profumo-fresco\\\/\",\"name\":\"profumo fresco Archivi - La Spezieria della Seta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/t\\\/profumo-fresco\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/t\\\/profumo-fresco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"profumo fresco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/#website\",\"url\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/\",\"name\":\"La Spezieria della Seta - Profumi di nicchia\",\"description\":\"Profumi di nicchia per persona e ambiente\",\"publisher\":{\"@id\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/#organization\"},\"alternateName\":\"La Spezieria della Seta - Profumi di nicchia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/#organization\",\"name\":\"La Spezieria della Seta\",\"url\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/logo-la-spezieria-della-seta.png\",\"contentUrl\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/logo-la-spezieria-della-seta.png\",\"width\":750,\"height\":750,\"caption\":\"La Spezieria della Seta\"},\"image\":{\"@id\":\"https:\\\/\\\/laspezieriadellaseta.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61573979611482\",\"https:\\\/\\\/www.instagram.com\\\/laspezieriadellaseta\",\"https:\\\/\\\/www.tiktok.com\\\/@laspezieriadellaseta\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"profumo fresco Archivi - La Spezieria della Seta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laspezieriadellaseta.it\/en\/t\/profumo-fresco\/","og_locale":"en_GB","og_type":"article","og_title":"profumo fresco Archivi - La Spezieria della Seta","og_url":"https:\/\/laspezieriadellaseta.it\/en\/t\/profumo-fresco\/","og_site_name":"La Spezieria della Seta","og_image":[{"width":1920,"height":1920,"url":"https:\/\/laspezieriadellaseta.it\/wp-content\/uploads\/2025\/01\/la-spezieria-della-seta-profumeria-artistica-soffio-duchaufour-G-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/laspezieriadellaseta.it\/t\/profumo-fresco\/","url":"https:\/\/laspezieriadellaseta.it\/t\/profumo-fresco\/","name":"profumo fresco Archivi - La Spezieria della Seta","isPartOf":{"@id":"https:\/\/laspezieriadellaseta.it\/#website"},"breadcrumb":{"@id":"https:\/\/laspezieriadellaseta.it\/t\/profumo-fresco\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/laspezieriadellaseta.it\/t\/profumo-fresco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/laspezieriadellaseta.it\/"},{"@type":"ListItem","position":2,"name":"profumo fresco"}]},{"@type":"WebSite","@id":"https:\/\/laspezieriadellaseta.it\/#website","url":"https:\/\/laspezieriadellaseta.it\/","name":"La Spezieria della Seta - Profumi di nicchia","description":"Profumi di nicchia per persona e ambiente","publisher":{"@id":"https:\/\/laspezieriadellaseta.it\/#organization"},"alternateName":"La Spezieria della Seta - Profumi di nicchia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laspezieriadellaseta.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/laspezieriadellaseta.it\/#organization","name":"La Spezieria della Seta","url":"https:\/\/laspezieriadellaseta.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/laspezieriadellaseta.it\/#\/schema\/logo\/image\/","url":"https:\/\/laspezieriadellaseta.it\/wp-content\/uploads\/2025\/03\/logo-la-spezieria-della-seta.png","contentUrl":"https:\/\/laspezieriadellaseta.it\/wp-content\/uploads\/2025\/03\/logo-la-spezieria-della-seta.png","width":750,"height":750,"caption":"La Spezieria della Seta"},"image":{"@id":"https:\/\/laspezieriadellaseta.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61573979611482","https:\/\/www.instagram.com\/laspezieriadellaseta","https:\/\/www.tiktok.com\/@laspezieriadellaseta"]}]}},"_links":{"self":[{"href":"https:\/\/laspezieriadellaseta.it\/en\/wp-json\/wp\/v2\/tags\/233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laspezieriadellaseta.it\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/laspezieriadellaseta.it\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/laspezieriadellaseta.it\/en\/wp-json\/wp\/v2\/posts?tags=233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}